{"id":283,"date":"2022-04-15T17:41:50","date_gmt":"2022-04-15T22:41:50","guid":{"rendered":"http:\/\/cherryhealthorg.local\/service\/basado-en-la-escuela\/"},"modified":"2026-07-10T08:26:12","modified_gmt":"2026-07-10T13:26:12","slug":"servicios-escueles","status":"publish","type":"service","link":"https:\/\/cherryhealth.org\/es\/services\/servicios-escueles\/","title":{"rendered":"Programas escolares"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Centros de salud en las escuelas<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Cherry Health colabora con las Escuelas P\u00fablicas de Grand Rapids, las Escuelas P\u00fablicas de Godwin Heights, Corewell Health y el Departamento de Salud y Servicios Sociales de M\u00edchigan para gestionar centros de salud en las propias escuelas. Estos centros ayudan a los alumnos a mejorar su asistencia y su rendimiento acad\u00e9mico ofreci\u00e9ndoles atenci\u00f3n m\u00e9dica, dental, asesoramiento y mucho m\u00e1s. <\/p>\n\n<p class=\"wp-block-paragraph\">Todos los j\u00f3venes y j\u00f3venes adultos de entre 5 y 21 a\u00f1os son bienvenidos, independientemente de su capacidad para pagar.  <em>Los ni\u00f1os de entre 3 y 4 a\u00f1os pueden ser considerados para recibir estos servicios en funci\u00f3n de sus s\u00edntomas.<\/em> <\/p>\n\n<p class=\"wp-block-paragraph\">Aceptamos Medicaid y la mayor\u00eda de los planes de seguro. Para quienes no tengan seguro, Cherry Health ofrece una escala de tarifas variable en funci\u00f3n de los ingresos del hogar y el tama\u00f1o de la familia.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Servicios disponibles:<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Revisiones pedi\u00e1tricas y reconocimientos m\u00e9dicos deportivos<\/li>\n\n\n\n<li>Tratamiento de lesiones y enfermedades<\/li>\n\n\n\n<li>Vacunas (se necesitan firmas adicionales)<\/li>\n\n\n\n<li>An\u00e1lisis de laboratorio rutinarios<\/li>\n\n\n\n<li>Medicamentos recetados en tu farmacia<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Con el consentimiento de los padres, los estudiantes pueden acceder a los servicios en los centros de salud de las siguientes escuelas:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/cherryhealth.org\/es\/locations\/centro-de-salud-del-instituto-godwin-heights\/\">Centro de Salud del Instituto Godwin Heights<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cherryhealth.org\/find-location\/innovation-central\/\">Centro de Salud de la Escuela Secundaria Central de Innovaci\u00f3n<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/cherryhealth.org\/find-location\/ottawa-hills-high-school-health-center\/\">Centro de salud de la escuela secundaria de Ottawa Hills<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cherryhealth.org\/find-location\/union-high-school-health-center\/\">Centro de salud de la escuela secundaria Union<\/a><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Servicios confidenciales:<\/strong> La legislaci\u00f3n de M\u00edchigan permite a los j\u00f3venes acceder a determinados servicios relacionados con la salud sexual, la salud mental y el consumo de sustancias sin necesidad de permiso de sus padres o tutores. No compartiremos con nadie las conversaciones confidenciales, los historiales ni los resultados de las pruebas sin el consentimiento del paciente.   <\/p>\n\n<p class=\"wp-block-paragraph\">Si quieres m\u00e1s informaci\u00f3n sobre los centros de salud escolares, llama al <a href=\"tel:6167765110\">616.776.5110<\/a> o env\u00eda un correo electr\u00f3nico <a href=\"&#x6d;&#x61;&#x69;&#x6c;&#116;&#111;&#58;&#83;BHC&#x40;&#x63;&#x68;&#x65;&#x72;&#114;&#121;&#104;eal&#x74;&#x68;&#x2e;&#x63;&#x6f;&#109;\" target=\"_blank\" rel=\"noreferrer noopener\">a &#x53;&#x42;&#x48;&#x43;&#x40;&#x63;&#x68;&#x65;&#x72;&#x72;&#x79;&#x68;&#x65;&#x61;&#x6c;&#x74;&#x68;&#x2e;&#x63;&#x6f;&#x6d;<\/a>.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cherryhealth.org\/wp-content\/uploads\/2025\/03\/School-Based-Health-Center-Consent-4165P.pdf\">Formulario de consentimiento del centro educativo<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cherryhealth.org\/wp-content\/uploads\/2025\/03\/School-Based-Health-Center-Consent-4165Psp.pdf\">Formulario de consentimiento para el centro escolar (espa\u00f1ol)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cherryhealth.org\/es\/recursos-para-pacientes\/formularios\/\">M\u00e1s formularios<\/a><\/div>\n<\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Servicios sanitarios vinculados a la escuela<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Nuestro programa de salud escolar itinerante es el primero de este tipo en M\u00edchigan y est\u00e1 pensado para que los alumnos se mantengan sanos, reduciendo las barreras y mejorando el acceso a la atenci\u00f3n sanitaria. Ofrece servicios dentales y oftalmol\u00f3gicos en m\u00e1s de 50 colegios de los siguientes distritos escolares: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Godfrey Lee<\/li>\n\n\n\n<li>Godwin Heights<\/li>\n\n\n\n<li>Gran Rapi\u00f1a<\/li>\n\n\n\n<li>Kelloggsville<\/li>\n\n\n\n<li>Kentwood<\/li>\n\n\n\n<li>Wyoming<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Los servicios dentales incluyen educaci\u00f3n dental, instrucci\u00f3n en higiene bucal, examen dental, radiograf\u00edas, limpieza dental, tratamiento con fl\u00faor, sellantes dentales y acceso a la atenci\u00f3n de seguimiento.<\/p>\n\n<p class=\"wp-block-paragraph\">Mientras tanto, nuestro programa See to Succeed ofrece ex\u00e1menes oculares completos con dilataci\u00f3n de pupilas y gafas graduadas a los ni\u00f1os con riesgo de sufrir problemas de visi\u00f3n. El programa ha proporcionado m\u00e1s de 21.500 ex\u00e1menes oculares y m\u00e1s de 6.000 pares de gafas a los estudiantes desde que lo pusimos en marcha en 2012. <\/p>\n\n<p class=\"wp-block-paragraph\">Si quieres m\u00e1s informaci\u00f3n sobre los servicios sanitarios vinculados a los colegios, llama al <a href=\"tel:6167762345\">616.776.2345<\/a> o env\u00eda un correo electr\u00f3nico <a href=\"m&#97;&#x69;&#x6c;t&#111;&#x3a;&#x53;c&#104;&#111;&#x6f;&#x6c;l&#105;&#x6e;&#x6b;e&#100;&#x68;&#x65;a&#108;&#116;&#x68;&#x70;r&#111;&#x67;&#x72;a&#109;&#x73;&#x40;C&#104;&#101;&#x72;&#x72;y&#72;&#x65;&#x61;l&#116;&#x68;&#x2e;c&#111;&#109;\" target=\"_blank\" rel=\"noreferrer noopener\">a S&#99;&#104;&#x6f;&#x6f;&#x6c;li&#110;&#107;&#x65;&#x64;&#x68;e&#97;&#108;&#116;&#x68;&#x70;&#x72;o&#103;&#114;&#x61;&#x6d;&#x73;&#64;C&#104;&#101;&#x72;&#x72;&#x79;H&#101;&#97;&#108;&#x74;&#x68;&#x2e;c&#111;&#109;<\/a>.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cherryhealth.org\/wp-content\/uploads\/2024\/03\/School-Linked-Dental-Treatment-Consent_Fillable-20215Psp.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Formulario de consentimiento para el servicio dental en el colegio<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cherryhealth.org\/wp-content\/uploads\/2024\/03\/School-Linked-Vision-Treatment-Consent_Fillable-20315Psp.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Formulario de consentimiento para el examen de la vista en el colegio<\/a><\/div>\n<\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Ampliaci\u00f3n, mejora de las escuelas de salud emocional (E3)<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">El programa \u00abExpanding, Enhancing Emotional Health\u00bb (E3) ofrece servicios integrales de salud mental (asesoramiento) ambulatorios presenciales a cualquier estudiante de los centros donde se imparte el programa. Todos los servicios los presta un profesional de la salud mental con t\u00edtulo de m\u00e1ster y colegiado, 40 horas a la semana. Se atiende a estudiantes con necesidades que van desde una gravedad leve hasta moderada. Los servicios incluyen derivaciones, seguimiento y atenci\u00f3n a lo largo de todo el a\u00f1o. Para recibir los servicios, es necesario un formulario de consentimiento firmado por un padre o tutor.    <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Cualquier alumno matriculado en el colegio E3 puede participar, independientemente de su capacidad econ\u00f3mica.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Servicios confidenciales: <\/strong>La ley <strong>de M\u00edchigan <\/strong>permite a los estudiantes de 14 a\u00f1os o m\u00e1s acceder a 12 sesiones de terapia sin necesidad de permiso de sus padres o tutores. Esto significa que las conversaciones, los historiales y los resultados de las pruebas de estas visitas confidenciales no se comparten con nadie. <\/p>\n\n<p class=\"wp-block-paragraph\">Se ofrecen servicios en los siguientes centros educativos:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/cherryhealth.org\/es\/locations\/escuela-secundaria-wyoming\/\">Escuela Secundaria Wyoming<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cherryhealth.org\/es\/locations\/escuela-secundaria-godwin-heights\/\">Escuela Secundaria Godwin Heights<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cherryhealth.org\/es\/locations\/escuela-secundaria-cedar-springs\/\">Escuela Secundaria Cedar Springs<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cherryhealth.org\/es\/locations\/escuela-secundaria-tri-county\/\">Escuela Secundaria Tri-County<\/a><\/li>\n<\/ul>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cherryhealth.org\/wp-content\/uploads\/2024\/06\/School-Based-Health-Center-Consent-Counseling-Services-4170Psp-Fillable.pdf\">Autorizaci\u00f3n para recibir servicios de asesoramiento<\/a><\/div>\n<\/div>\n","protected":false},"parent":0,"template":"","class_list":["post-283","service","type-service","status-publish","hentry"],"acf":[],"title_raw":"Programas escolares","_links":{"self":[{"href":"https:\/\/cherryhealth.org\/es\/wp-json\/wp\/v2\/service\/283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cherryhealth.org\/es\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/cherryhealth.org\/es\/wp-json\/wp\/v2\/types\/service"}],"wp:attachment":[{"href":"https:\/\/cherryhealth.org\/es\/wp-json\/wp\/v2\/media?parent=283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}